{"id":11353,"date":"2023-09-22T08:42:00","date_gmt":"2023-09-22T06:42:00","guid":{"rendered":"https:\/\/adntro.com\/?p=11353"},"modified":"2025-07-28T08:26:20","modified_gmt":"2025-07-28T06:26:20","slug":"genetica-lesiones-parte1","status":"publish","type":"post","link":"https:\/\/adntro.com\/de\/blog\/sport\/genetik-verletzungen-teil1\/","title":{"rendered":"Spielt die Genetik bei Verletzungen eine Rolle? Teil 1"},"content":{"rendered":"<p class=\"wp-block-paragraph translation-block\">Mit der <strong>R\u00fcckkehr des Sommers,<\/strong> nehmen viele Sportler und Sportbegeisterte ihre k\u00f6rperlichen Aktivit\u00e4ten mit neuer Energie und Motivation wieder auf. Doch diese Zeit kann auch <strong>eine Zunahme von Sportverletzungen mit sich bringen. <\/strong>W\u00e4hrend Trainingsmethoden und die richtige Ausr\u00fcstung eine entscheidende Rolle bei der Verletzungspr\u00e4vention spielen, gibt es einen weiteren Faktor, der oft unbeachtet bleibt: der Einfluss der Genetik auf Sportverletzungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Ja, <strong>Ihre Genetik hat einen Einfluss <\/strong>auf Ihre Anf\u00e4lligkeit f\u00fcr <strong>bestimmte Arten von Verletzungen<\/strong> wie Achillessehnen- und Kn\u00f6chelverletzungen.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/runner_dna.png\" alt=\"Der Einfluss der Genetik auf Verletzungen\" class=\"wp-image-11357\" style=\"width:-62px;height:-62px\" srcset=\"https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/runner_dna.png 1024w, https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/runner_dna-300x300.png 300w, https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/runner_dna-150x150.png 150w, https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/runner_dna-768x768.png 768w, https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/runner_dna-12x12.png 12w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Kn\u00f6chelverletzungen<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Wenn wir von Kn\u00f6chelverletzungen sprechen, meinen wir <strong>Verstauchungen, Zerrungen und andere Gelenk- oder Instabilit\u00e4tsst\u00f6rungen<\/strong>. Kn\u00f6chelverletzungen sind h\u00e4ufig, vor allem bei Sportlern, die Hallen- oder Sprungsportarten betreiben. Sie betreffen die B\u00e4nder und Muskeln rund um den Kn\u00f6chel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EIN <strong>Muskelzerrung am Kn\u00f6chel<\/strong> ist eine Verletzung oder \u00dcberdehnung der Muskeln oder Sehnen, die den Kn\u00f6chel umgeben. Muskelzerrungen <strong>k\u00f6nnen unterschiedlich stark ausgepr\u00e4gt sein<\/strong>Die Bandbreite der Symptome reicht von einer leichten Zerrung mit Unbehagen und Steifheit bis hin zu einem vollst\u00e4ndigen Riss des Muskels oder der Sehne mit starken Schmerzen und der Unf\u00e4higkeit, den Kn\u00f6chel zu bewegen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Eine <strong>Kn\u00f6chelverstauchung<\/strong> entsteht, wenn die B\u00e4nder, die die Kn\u00f6chelknochen verbinden, durch \u00fcberm\u00e4\u00dfige Kraft oder pl\u00f6tzliche Bewegung gedehnt werden oder rei\u00dfen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Symptome von Kn\u00f6chelverletzungen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Zu den h\u00e4ufigen Symptomen von Verstauchungen und Zerrungen des Kn\u00f6chels geh\u00f6ren <strong>Schmerzen, Schwellungen, Bluterg\u00fcsse, Schwierigkeiten, den Kn\u00f6chel zu bewegen, Ber\u00fchrungsempfindlichkeit und R\u00f6tung im betroffenen Bereich<\/strong>. Die Erstbehandlung dieser Verletzungen umfasst in der Regel Ruhe, Vereisung, Kompression und Hochlagerung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ursachen von Kn\u00f6chelverletzungen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Eine Verstauchung des Sprunggelenks liegt vor, wenn <strong>die B\u00e4nder des Sprunggelenks<\/strong>, vor allem der seitliche Bandkomplex, verletzt werden. Kn\u00f6chelverletzungen werden in der Regel durch <strong>Bewegungen des Kn\u00f6chels verursacht, die ihn aus der Achse bringen<\/strong> (eine akute Eversion oder Inversion des Kn\u00f6chels).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Wie die Genetik bei Kn\u00f6chelverletzungen eine Rolle spielt<\/strong>?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Obwohl Kn\u00f6chelverletzungen in der Regel durch <strong>Bewegungen des Kn\u00f6chels, die ihn aus der Achse bringen<\/strong>, verursacht werden, k\u00f6nnen bestimmte Personen ein erh\u00f6htes Verletzungsrisiko nach einem solchen Trauma haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Es wurden mehrere Risikofaktoren beschrieben (unebener Untergrund, ungeeignetes Schuhwerk...), aber auch die <strong>Genetik<\/strong> des Einzelnen kann <strong>das Risiko einer Kn\u00f6chelverletzung<\/strong> beeinflussen, ebenso wie die Schwere der Verletzung und die Geschwindigkeit der Genesung. Diese Personen k\u00f6nnen ihr Risiko durch pr\u00e4ventives Training, angepasste Konditionierung und geeignetes Schuhwerk verringern.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/tobillos_ballet-1024x574.png\" alt=\"Kn\u00f6chelverletzungen\" class=\"wp-image-11355\" style=\"width:531px;height:297px\" srcset=\"https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/tobillos_ballet-1024x574.png 1024w, https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/tobillos_ballet-300x168.png 300w, https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/tobillos_ballet-768x430.png 768w, https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/tobillos_ballet-18x10.png 18w, https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/tobillos_ballet.png 1456w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Achillessehne<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Die Achillessehne ist die <strong>gr\u00f6\u00dfte und st\u00e4rkste Sehne im menschlichen K\u00f6rper<\/strong>, die die Wadenmuskeln mit dem Fersenbein verbindet. Ihre <strong>Hauptfunktion ist es, die Beugung des Fu\u00dfes zu erm\u00f6glichen<\/strong> und den Vortrieb beim Gehen, Laufen und Springen zu unterst\u00fctzen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Welche Arten von Verletzungen kann die Achillessehne erleiden?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Die Achillessehne kann einen <strong>Riss<\/strong> erleiden oder eine <strong>Tendinopathie<\/strong> aufweisen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Tendinopathie<\/strong> ist ein Oberbegriff, der sowohl <strong>entz\u00fcndliche<\/strong> (Tendinitis) als auch <strong>degenerative<\/strong> (Tendinose) Probleme umfasst. Diese k\u00f6nnen durch intensive sportliche Aktivit\u00e4ten, Laufen auf hartem Untergrund, pl\u00f6tzliche \u00c4nderungen der Trainingsintensit\u00e4t, Verwendung von ungeeignetem Schuhwerk oder altersbedingte Schw\u00e4chung auftreten. Zu den <strong>Symptomen<\/strong> geh\u00f6ren Schmerzen und Z\u00e4rtlichkeit in der Achillessehne, Morgensteifigkeit und Schwierigkeiten beim Gehen oder Laufen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">&lt;Eine Achillessehnenruptur kann durch eine pl\u00f6tzliche Krafteinwirkung auf die Sehne (z. B. durch einen Sturz aus gro\u00dfer H\u00f6he), durch ein Trauma der Sehne oder durch eine chronische Tendinitis, die das Sehnengewebe schw\u00e4cht, entstehen. Am h\u00e4ufigsten tritt sie bei Menschen mittleren Alters und bei Sportlern auf, die schnelle Richtungswechsel ausf\u00fchren. Zu den <strong>Symptomen<\/strong> einer gerissenen Achillessehne geh\u00f6ren ein \"schnappendes\" oder \"knallendes\" Ger\u00e4usch in der R\u00fcckseite des Beins, starke Schmerzen, Schwellungen, Schwierigkeiten beim Gehen oder Zehenspitzenstehen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Welchen Einfluss hat die Genetik auf Achillessehnenverletzungen?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph translation-block\"><strong>Es gibt genetische Marker, die das individuelle Risiko einer Achillessehnenverletzung vorhersagen k\u00f6nnen<\/strong>. Die Rolle von genetischen Polymorphismen (<a href=\"https:\/\/adntro.com\/es\/blog\/aprende-genetica\/que-son-los-snps\/\" target=\"_blank\" rel=\"noreferrer noopener\">SNPs<\/a>) in <strong>Genen, die mit der Struktur und Funktion der Sehne zusammenh\u00e4ngen, wie Typ-V-Kollagen und Matrix-Metalloproteinasen (MMPs)<\/strong>, wurde untersucht.<\/p>\n\n\n\n<div style=\"height:41px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Deshalb kann die Kenntnis Ihrer genetischen Veranlagung f\u00fcr Sportverletzungen Verletzungen vorbeugen und Ihnen helfen, Ihren K\u00f6rper besser zu verstehen und intelligenter und sicherer zu trainieren. Entdecken Sie die <a href=\"https:\/\/app.adntro.com\/fitness\/injuries?event_label=menu\" target=\"_blank\" rel=\"noreferrer noopener\">Einfluss der Genetik auf Sportverletzungen<\/a> mit dem <a href=\"https:\/\/adntro.com\/de\/\">DNA-TEST<\/a> von ADNTRO! Wenn Sie bereits genotypisiert sind, denken Sie daran, dass Sie <a href=\"https:\/\/adntro.com\/de\/upload-your-raw\/\">Ihre Rohdatei kostenlos hochladen<\/a>. <\/p>","protected":false},"excerpt":{"rendered":"<p>Mit der R\u00fcckkehr des Sommers nehmen viele Sportler und Sportbegeisterte ihre k\u00f6rperlichen Aktivit\u00e4ten mit neuer Energie und Motivation wieder auf. Diese Zeit des Jahres kann jedoch auch eine erh\u00f6hte Anzahl von Sportverletzungen mit sich bringen. W\u00e4hrend Trainingsmethoden und die richtige Ausr\u00fcstung eine entscheidende Rolle bei der Verletzungsvorbeugung spielen, gibt es noch eine weitere [...]<\/p>","protected":false},"author":8,"featured_media":11355,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[431],"tags":[42,519,53,18,516,20,518,517,93],"class_list":["post-11353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-adntro","tag-colageno","tag-deporte","tag-genetica","tag-lesiones","tag-snp","tag-tendon-de-aquiles","tag-tobillo","tag-variantes-geneticas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Influencia de la gen\u00e9tica en las lesiones. Parte 1<\/title>\n<meta name=\"description\" content=\"\u00bfInteresado en la influencia de la gen\u00e9tica en las lesiones deportivas? Descubre todo acerca de las lesiones de tobillo y el tend\u00f3n de Aquiles\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adntro.com\/de\/blog\/sport\/genetik-verletzungen-teil1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Influencia de la gen\u00e9tica en las lesiones. Parte 1\" \/>\n<meta property=\"og:description\" content=\"\u00bfInteresado en la influencia de la gen\u00e9tica en las lesiones deportivas? Descubre todo acerca de las lesiones de tobillo y el tend\u00f3n de Aquiles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adntro.com\/de\/blog\/sport\/genetik-verletzungen-teil1\/\" \/>\n<meta property=\"og:site_name\" content=\"ADNTRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADNTROSPAIN\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-22T06:42:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T06:26:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/tobillos_ballet.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sandra Ferreiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@adntrospain\" \/>\n<meta name=\"twitter:site\" content=\"@adntrospain\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Ferreiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/adntro.com\/es\/blog\/deporte\/genetica-lesiones-parte1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/adntro.com\/en\/blog\/sport\/genetics-injuries-part1\/\"},\"author\":{\"name\":\"Sandra Ferreiro\",\"@id\":\"https:\/\/adntro.com\/es\/#\/schema\/person\/4610b32ed534df61fd3a557dca61e197\"},\"headline\":\"\u00bfInfluye la gen\u00e9tica en las lesiones? Parte 1\",\"datePublished\":\"2023-09-22T06:42:00+00:00\",\"dateModified\":\"2025-07-28T06:26:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/adntro.com\/en\/blog\/sport\/genetics-injuries-part1\/\"},\"wordCount\":864,\"publisher\":{\"@id\":\"https:\/\/adntro.com\/es\/#organization\"},\"keywords\":[\"adntro\",\"col\u00e1geno\",\"deporte\",\"gen\u00e9tica\",\"lesiones\",\"SNP\",\"tend\u00f3n de Aquiles\",\"tobillo\",\"variantes gen\u00e9ticas\"],\"articleSection\":[\"Deporte\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/adntro.com\/en\/blog\/sport\/genetics-injuries-part1\/\",\"url\":\"https:\/\/adntro.com\/es\/blog\/deporte\/genetica-lesiones-parte1\/\",\"name\":\"Influencia de la gen\u00e9tica en las lesiones. Parte 1\",\"isPartOf\":{\"@id\":\"https:\/\/adntro.com\/es\/#website\"},\"datePublished\":\"2023-09-22T06:42:00+00:00\",\"dateModified\":\"2025-07-28T06:26:20+00:00\",\"description\":\"\u00bfInteresado en la influencia de la gen\u00e9tica en las lesiones deportivas? Descubre todo acerca de las lesiones de tobillo y el tend\u00f3n de Aquiles\",\"breadcrumb\":{\"@id\":\"https:\/\/adntro.com\/es\/blog\/deporte\/genetica-lesiones-parte1\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/adntro.com\/es\/blog\/deporte\/genetica-lesiones-parte1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/adntro.com\/es\/blog\/deporte\/genetica-lesiones-parte1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/adntro.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfInfluye la gen\u00e9tica en las lesiones? Parte 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/adntro.com\/es\/#website\",\"url\":\"https:\/\/adntro.com\/es\/\",\"name\":\"ADNTRO\",\"description\":\"Gen\u00e9tica, salud, nutrici\u00f3n\",\"publisher\":{\"@id\":\"https:\/\/adntro.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/adntro.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/adntro.com\/es\/#organization\",\"name\":\"ADNTRO Genetics\",\"url\":\"https:\/\/adntro.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/adntro.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/adntro.com\/wp-content\/uploads\/2021\/08\/android-chrome-512x512-2.png\",\"contentUrl\":\"https:\/\/adntro.com\/wp-content\/uploads\/2021\/08\/android-chrome-512x512-2.png\",\"width\":512,\"height\":512,\"caption\":\"ADNTRO Genetics\"},\"image\":{\"@id\":\"https:\/\/adntro.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ADNTROSPAIN\/\",\"https:\/\/twitter.com\/adntrospain\",\"https:\/\/www.instagram.com\/adntro_\/\",\"https:\/\/www.pinterest.es\/ADNTRO_TEAM\/_saved\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/adntro.com\/es\/#\/schema\/person\/4610b32ed534df61fd3a557dca61e197\",\"name\":\"Sandra Ferreiro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/adntro.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ddaa4448bc53192d65c596cd5119749fb4d7167a3b3d7931d8b0470a2021bdc3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ddaa4448bc53192d65c596cd5119749fb4d7167a3b3d7931d8b0470a2021bdc3?s=96&d=mm&r=g\",\"caption\":\"Sandra Ferreiro\"},\"description\":\"Bioinform\u00e1tica y Responsable del \u00e1rea cient\u00edfica en ADNTRO. Biotecn\u00f3loga por la Universidad Francisco de Vitoria, donde recibi\u00f3 dos becas de expediente acad\u00e9mico brillante. Estuvo trabajando en un proyecto de investigaci\u00f3n sobre la asimetr\u00eda izquierda-derecha en Newcastle, siendo premiada en la Conferencia del Centro de Investigaci\u00f3n Cardiovascular Trainees Meeting como el mejor p\u00f3ster (2018). Complet\u00f3 un m\u00e1ster en Biolog\u00eda Computacional en la Universidad Polit\u00e9cnica de Madrid. All\u00ed estudi\u00f3 las redes de interacci\u00f3n metab\u00f3lica en el microbioma de pacientes con Enfermedad de Chron y Colitis Ulcerosa en el centro de investigaci\u00f3n CBGP, centro de Excelencia Severo Ochoa (2020). Desde el 2020 es Bioinform\u00e1tica en ADNTRO donde desarrolla modelos predictivos, realiza anotaciones y an\u00e1lisis de variantes patog\u00e9nicas, investigaci\u00f3n de literatura GWAS y divulgaci\u00f3n cient\u00edfica.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/sandra-ferreiro-lpez-78804016a\/\"],\"url\":\"https:\/\/adntro.com\/de\/blog\/author\/sandra\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Influencia de la gen\u00e9tica en las lesiones. Parte 1","description":"\u00bfInteresado en la influencia de la gen\u00e9tica en las lesiones deportivas? Descubre todo acerca de las lesiones de tobillo y el tend\u00f3n de Aquiles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adntro.com\/de\/blog\/sport\/genetik-verletzungen-teil1\/","og_locale":"de_DE","og_type":"article","og_title":"Influencia de la gen\u00e9tica en las lesiones. Parte 1","og_description":"\u00bfInteresado en la influencia de la gen\u00e9tica en las lesiones deportivas? Descubre todo acerca de las lesiones de tobillo y el tend\u00f3n de Aquiles","og_url":"https:\/\/adntro.com\/de\/blog\/sport\/genetik-verletzungen-teil1\/","og_site_name":"ADNTRO","article_publisher":"https:\/\/www.facebook.com\/ADNTROSPAIN\/","article_published_time":"2023-09-22T06:42:00+00:00","article_modified_time":"2025-07-28T06:26:20+00:00","og_image":[{"width":1456,"height":816,"url":"https:\/\/adntro.com\/wp-content\/uploads\/2023\/08\/tobillos_ballet.png","type":"image\/png"}],"author":"Sandra Ferreiro","twitter_card":"summary_large_image","twitter_creator":"@adntrospain","twitter_site":"@adntrospain","twitter_misc":{"Verfasst von":"Sandra Ferreiro","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adntro.com\/es\/blog\/deporte\/genetica-lesiones-parte1\/#article","isPartOf":{"@id":"https:\/\/adntro.com\/en\/blog\/sport\/genetics-injuries-part1\/"},"author":{"name":"Sandra Ferreiro","@id":"https:\/\/adntro.com\/es\/#\/schema\/person\/4610b32ed534df61fd3a557dca61e197"},"headline":"\u00bfInfluye la gen\u00e9tica en las lesiones? Parte 1","datePublished":"2023-09-22T06:42:00+00:00","dateModified":"2025-07-28T06:26:20+00:00","mainEntityOfPage":{"@id":"https:\/\/adntro.com\/en\/blog\/sport\/genetics-injuries-part1\/"},"wordCount":864,"publisher":{"@id":"https:\/\/adntro.com\/es\/#organization"},"keywords":["adntro","col\u00e1geno","deporte","gen\u00e9tica","lesiones","SNP","tend\u00f3n de Aquiles","tobillo","variantes gen\u00e9ticas"],"articleSection":["Deporte"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/adntro.com\/en\/blog\/sport\/genetics-injuries-part1\/","url":"https:\/\/adntro.com\/es\/blog\/deporte\/genetica-lesiones-parte1\/","name":"Influencia de la gen\u00e9tica en las lesiones. Parte 1","isPartOf":{"@id":"https:\/\/adntro.com\/es\/#website"},"datePublished":"2023-09-22T06:42:00+00:00","dateModified":"2025-07-28T06:26:20+00:00","description":"\u00bfInteresado en la influencia de la gen\u00e9tica en las lesiones deportivas? Descubre todo acerca de las lesiones de tobillo y el tend\u00f3n de Aquiles","breadcrumb":{"@id":"https:\/\/adntro.com\/es\/blog\/deporte\/genetica-lesiones-parte1\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adntro.com\/es\/blog\/deporte\/genetica-lesiones-parte1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adntro.com\/es\/blog\/deporte\/genetica-lesiones-parte1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adntro.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfInfluye la gen\u00e9tica en las lesiones? Parte 1"}]},{"@type":"WebSite","@id":"https:\/\/adntro.com\/es\/#website","url":"https:\/\/adntro.com\/es\/","name":"ADNTRO","description":"Gen\u00e9tica, salud, nutrici\u00f3n","publisher":{"@id":"https:\/\/adntro.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adntro.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/adntro.com\/es\/#organization","name":"ADNTRO Genetics","url":"https:\/\/adntro.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/adntro.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/adntro.com\/wp-content\/uploads\/2021\/08\/android-chrome-512x512-2.png","contentUrl":"https:\/\/adntro.com\/wp-content\/uploads\/2021\/08\/android-chrome-512x512-2.png","width":512,"height":512,"caption":"ADNTRO Genetics"},"image":{"@id":"https:\/\/adntro.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ADNTROSPAIN\/","https:\/\/twitter.com\/adntrospain","https:\/\/www.instagram.com\/adntro_\/","https:\/\/www.pinterest.es\/ADNTRO_TEAM\/_saved\/"]},{"@type":"Person","@id":"https:\/\/adntro.com\/es\/#\/schema\/person\/4610b32ed534df61fd3a557dca61e197","name":"Sandra Ferreiro","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/adntro.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ddaa4448bc53192d65c596cd5119749fb4d7167a3b3d7931d8b0470a2021bdc3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ddaa4448bc53192d65c596cd5119749fb4d7167a3b3d7931d8b0470a2021bdc3?s=96&d=mm&r=g","caption":"Sandra Ferreiro"},"description":"Bioinform\u00e1tica y Responsable del \u00e1rea cient\u00edfica en ADNTRO. Biotecn\u00f3loga por la Universidad Francisco de Vitoria, donde recibi\u00f3 dos becas de expediente acad\u00e9mico brillante. Estuvo trabajando en un proyecto de investigaci\u00f3n sobre la asimetr\u00eda izquierda-derecha en Newcastle, siendo premiada en la Conferencia del Centro de Investigaci\u00f3n Cardiovascular Trainees Meeting como el mejor p\u00f3ster (2018). Complet\u00f3 un m\u00e1ster en Biolog\u00eda Computacional en la Universidad Polit\u00e9cnica de Madrid. All\u00ed estudi\u00f3 las redes de interacci\u00f3n metab\u00f3lica en el microbioma de pacientes con Enfermedad de Chron y Colitis Ulcerosa en el centro de investigaci\u00f3n CBGP, centro de Excelencia Severo Ochoa (2020). Desde el 2020 es Bioinform\u00e1tica en ADNTRO donde desarrolla modelos predictivos, realiza anotaciones y an\u00e1lisis de variantes patog\u00e9nicas, investigaci\u00f3n de literatura GWAS y divulgaci\u00f3n cient\u00edfica.","sameAs":["https:\/\/www.linkedin.com\/in\/sandra-ferreiro-lpez-78804016a\/"],"url":"https:\/\/adntro.com\/de\/blog\/author\/sandra\/"}]}},"_links":{"self":[{"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/posts\/11353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/comments?post=11353"}],"version-history":[{"count":5,"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/posts\/11353\/revisions"}],"predecessor-version":[{"id":13242,"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/posts\/11353\/revisions\/13242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/media\/11355"}],"wp:attachment":[{"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/media?parent=11353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/categories?post=11353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adntro.com\/de\/wp-json\/wp\/v2\/tags?post=11353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}